{"id":26537,"date":"2024-02-05T18:18:10","date_gmt":"2024-02-05T17:18:10","guid":{"rendered":"https:\/\/22hbg.com\/conoce-el-22hbg\/"},"modified":"2026-03-30T17:17:52","modified_gmt":"2026-03-30T16:17:52","slug":"conoce-el-22hbg","status":"publish","type":"page","link":"https:\/\/22hbg.com\/es\/conoce-el-22hbg\/","title":{"rendered":"Conoce el 22HBG"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"26537\" class=\"elementor elementor-26537 elementor-2324\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ba270ea elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"ba270ea\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-64ee69d\" data-id=\"64ee69d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-10eeadc elementor-widget elementor-widget-image\" data-id=\"10eeadc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/22hbg.com\/wp-content\/uploads\/2025\/01\/cropped-22hbg_favicon_logo.png\" class=\"attachment-large size-large wp-image-24892\" alt=\"22HBG\" srcset=\"https:\/\/22hbg.com\/wp-content\/uploads\/2025\/01\/cropped-22hbg_favicon_logo.png 512w, https:\/\/22hbg.com\/wp-content\/uploads\/2025\/01\/cropped-22hbg_favicon_logo-300x300.png 300w, https:\/\/22hbg.com\/wp-content\/uploads\/2025\/01\/cropped-22hbg_favicon_logo-150x150.png 150w, https:\/\/22hbg.com\/wp-content\/uploads\/2025\/01\/cropped-22hbg_favicon_logo-500x500.png 500w, https:\/\/22hbg.com\/wp-content\/uploads\/2025\/01\/cropped-22hbg_favicon_logo-384x384.png 384w, https:\/\/22hbg.com\/wp-content\/uploads\/2025\/01\/cropped-22hbg_favicon_logo-320x320.png 320w, https:\/\/22hbg.com\/wp-content\/uploads\/2025\/01\/cropped-22hbg_favicon_logo-100x100.png 100w, https:\/\/22hbg.com\/wp-content\/uploads\/2025\/01\/cropped-22hbg_favicon_logo-270x270.png 270w, https:\/\/22hbg.com\/wp-content\/uploads\/2025\/01\/cropped-22hbg_favicon_logo-192x192.png 192w, https:\/\/22hbg.com\/wp-content\/uploads\/2025\/01\/cropped-22hbg_favicon_logo-180x180.png 180w, https:\/\/22hbg.com\/wp-content\/uploads\/2025\/01\/cropped-22hbg_favicon_logo-32x32.png 32w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8d9388c\" data-id=\"8d9388c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e2c808e elementor-widget elementor-widget-neuros_heading\" data-id=\"e2c808e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"neuros_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"neuros-heading-widget\"><h2 class=\"neuros-heading\"><span class=\"neuros-heading-content has_gradient_color_text\">22HBG. <del>Empresa tecnol\u00f3gica<\/del>. Visi\u00f3n <del>italiana<\/del>, ambici\u00f3n <del>global<\/del> \n<\/span><\/h2><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a33bd19 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a33bd19\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b37b706\" data-id=\"b37b706\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-63200c9 elementor-invisible elementor-widget elementor-widget-neuros_heading\" data-id=\"63200c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;neuros_heading_animation&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"neuros_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"neuros-heading-widget\"><h2 class=\"neuros-heading\"><span class=\"neuros-subheading\">sobre nosotros<\/span><span class=\"neuros-heading-content has_gradient_color_text\">Donde confluyen tecnolog\u00eda, visi\u00f3n y concreci\u00f3n<\/span><\/h2><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b74fafe elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b74fafe\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-f05c030\" data-id=\"f05c030\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7d34628 elementor-widget elementor-widget-text-editor\" data-id=\"7d34628\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"69\" data-end=\"313\"><strong>Somos una empresa tecnol\u00f3gica italiana que desarrolla soluciones de software y sistemas digitales para medios de comunicaci\u00f3n, radiodifusi\u00f3n y tecnolog\u00edas inteligentes. Cada proyecto nace de un an\u00e1lisis concreto y se traduce en una tecnolog\u00eda escalable, sostenible y de gran impacto. <\/strong><\/p><p data-start=\"315\" data-end=\"532\" data-is-last-node=\"\" data-is-only-node=\"\">Para nosotros, innovar es un proceso, no un eslogan. Trabajamos con mentalidad ingenieril y visi\u00f3n empresarial, integrando IA, nube y dispositivos inteligentes para ofrecer a nuestros socios una ventaja competitiva real. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-673c99f elementor-widget__width-auto e-transform e-transform elementor-absolute elementor-widget elementor-widget-neuros_special_text\" data-id=\"673c99f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_rotateZ_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:-90,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:-100,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_laptop&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_tablet_extra&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_mobile_extra&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_position&quot;:&quot;absolute&quot;,&quot;_transform_translateY_effect&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_laptop&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_tablet_extra&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_mobile_extra&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_widescreen&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_laptop&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_tablet_extra&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_tablet&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_mobile_extra&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_mobile&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_widescreen&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_widescreen&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"neuros_special_text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"special-text-wrapper\"><div class=\"special-text special-text-effect-fill\">N\u00facleo<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d0612c4\" data-id=\"d0612c4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c25890b elementor-widget elementor-widget-image\" data-id=\"c25890b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"711\" src=\"https:\/\/22hbg.com\/wp-content\/uploads\/2025\/06\/office-wall.webp\" class=\"attachment-large size-large wp-image-24997\" alt=\"\" srcset=\"https:\/\/22hbg.com\/wp-content\/uploads\/2025\/06\/office-wall.webp 400w, https:\/\/22hbg.com\/wp-content\/uploads\/2025\/06\/office-wall-169x300.webp 169w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b81d1f2 elementor-section-full_width elementor-section-stretched elementor-section-container-padding-remove elementor-section-height-default elementor-section-height-default\" data-id=\"b81d1f2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c073aa8\" data-id=\"c073aa8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2c05e96 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2c05e96\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-9d6f20a\" data-id=\"9d6f20a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e04419c elementor-invisible elementor-widget elementor-widget-neuros_heading\" data-id=\"e04419c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;neuros_heading_animation&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"neuros_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"neuros-heading-widget\"><h2 class=\"neuros-heading\"><span class=\"neuros-subheading\">sobre nosotros<\/span><span class=\"neuros-heading-content has_gradient_color_text\">El m\u00e9todo de los 100 d\u00edas. Innovaci\u00f3n concreta, no promesas. <\/span><\/h2><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7cd8f7f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7cd8f7f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-2f8a170\" data-id=\"2f8a170\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4e50563 elementor-widget elementor-widget-text-editor\" data-id=\"4e50563\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"1234\" data-end=\"1466\"><strong>Cada proyecto empieza con un reto. Analizamos tu mercado, identificamos los problemas cr\u00edticos y desarrollamos soluciones a medida capaces de generar un valor mensurable en 100 d\u00edas. Ning\u00fan efecto sorpresa temporal, s\u00f3lo resultados tangibles.  <\/strong><\/p><p data-start=\"1468\" data-end=\"1763\">Nos asociamos con empresas que creen en la transformaci\u00f3n digital a trav\u00e9s de los n\u00fameros, la tecnolog\u00eda y el pragmatismo. Desde la supervisi\u00f3n remota de transmisores hasta el lanzamiento de aplicaciones de radio y Canal R\u00c1PIDO, desde el control distribuido en redes nacionales hasta la personalizaci\u00f3n de la experiencia del usuario mediante IA. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a25f7f8 elementor-widget__width-auto e-transform e-transform elementor-absolute elementor-widget elementor-widget-neuros_special_text\" data-id=\"a25f7f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_rotateZ_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:-90,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:-100,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_laptop&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_tablet_extra&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_mobile_extra&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_position&quot;:&quot;absolute&quot;,&quot;_transform_translateY_effect&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_laptop&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_tablet_extra&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_mobile_extra&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_widescreen&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_laptop&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_tablet_extra&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_tablet&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_mobile_extra&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_mobile&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_widescreen&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_widescreen&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"neuros_special_text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"special-text-wrapper\"><div class=\"special-text special-text-effect-fill\">100<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fbd82db elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fbd82db\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ca856b1\" data-id=\"ca856b1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ff2c1c6 elementor-widget elementor-widget-neuros_heading\" data-id=\"ff2c1c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"neuros_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"neuros-heading-widget\"><h2 class=\"neuros-heading\"><span class=\"neuros-subheading\">nuestros proyectos<\/span><span class=\"neuros-heading-content has_gradient_color_text\">Casos pr\u00e1cticos<\/span><\/h2><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-318e44f listing-pagination-border-style-gradient listing-pagination-background-style-solid elementor-widget elementor-widget-neuros_case_study_listing\" data-id=\"318e44f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"neuros_case_study_listing.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n            <div class=\"archive-listing\" data-ajax='{&quot;post_type&quot;:&quot;neuros_case_study&quot;,&quot;posts_per_page&quot;:3,&quot;ignore_sticky_posts&quot;:true,&quot;suppress_filters&quot;:false,&quot;orderby&quot;:&quot;date&quot;,&quot;order&quot;:&quot;desc&quot;,&quot;link_base&quot;:&quot;https:\\\/\\\/22hbg.com\\\/es\\\/wp-json\\\/wp\\\/v2\\\/pages\\\/26537\\\/&quot;,&quot;paged&quot;:1}' data-widget='{&quot;show_media&quot;:&quot;yes&quot;,&quot;show_date&quot;:&quot;&quot;,&quot;show_name&quot;:&quot;yes&quot;,&quot;show_tags&quot;:&quot;&quot;,&quot;listing_type&quot;:&quot;grid&quot;,&quot;show_pagination&quot;:&quot;yes&quot;,&quot;item_class&quot;:&quot;grid-blog-item-wrapper&quot;,&quot;columns_number&quot;:3}'>\n                <div class=\"archive-listing-wrapper case-study-listing-wrapper case-study-grid-listing columns-3\">\n                    \n<div class=\"grid-blog-item-wrapper post-30843 neuros_case_study type-neuros_case_study status-publish has-post-thumbnail hentry neuros_case_study_category-brand neuros_case_study_tag-caracteristicas-personalizadas neuros_case_study_tag-marca neuros_case_study_tag-sincronizado\">\n    <div class=\"case-study-item\">\n        <h4 class=\"post-title\"><a href=\"https:\/\/22hbg.com\/es\/case-studies\/icoone-touch\/\">icoone Touch<\/a><\/h4><div class=\"post-media-wrapper\"><a href=\"https:\/\/22hbg.com\/es\/case-studies\/icoone-touch\/\"><picture><source media=\"(max-width: 575px)\" sizes=\"(max-width: 575px) 575px\" srcset=\"https:\/\/22hbg.com\/wp-content\/uploads\/2026\/02\/Frame-29-575x274.jpg 575w\"><source media=\"(max-width: 991px)\" sizes=\"(max-width: 991px) 991px\" srcset=\"https:\/\/22hbg.com\/wp-content\/uploads\/2026\/02\/Frame-29-500x374.jpg 991w\"><img decoding=\"async\" alt=\"Frame 29\" title=\"Frame 29\" src=\"https:\/\/22hbg.com\/wp-content\/uploads\/2026\/02\/Frame-29-640x478.jpg\" class=\"attachment-neuros_post_grid_3_columns size-neuros_post_grid_3_columns wp-post-image\" \/><\/picture><\/a><\/div>    <\/div>\n<\/div>\n<div class=\"grid-blog-item-wrapper post-30855 neuros_case_study type-neuros_case_study status-publish has-post-thumbnail hentry neuros_case_study_category-smart-tv-es neuros_case_study_tag-caracteristicas-personalizadas neuros_case_study_tag-cms neuros_case_study_tag-sincronizado neuros_case_study_tag-smart-tv-es neuros_case_study_tag-tv-fuego\">\n    <div class=\"case-study-item\">\n        <h4 class=\"post-title\"><a href=\"https:\/\/22hbg.com\/es\/case-studies\/naturhouse-tv\/\">Naturhouse TV<\/a><\/h4><div class=\"post-media-wrapper\"><a href=\"https:\/\/22hbg.com\/es\/case-studies\/naturhouse-tv\/\"><picture><source media=\"(max-width: 575px)\" sizes=\"(max-width: 575px) 575px\" srcset=\"https:\/\/22hbg.com\/wp-content\/uploads\/2026\/02\/Frame-26-1-575x274.jpg 575w\"><source media=\"(max-width: 991px)\" sizes=\"(max-width: 991px) 991px\" srcset=\"https:\/\/22hbg.com\/wp-content\/uploads\/2026\/02\/Frame-26-1-500x374.jpg 991w\"><img decoding=\"async\" alt=\"Cuadro 26\" title=\"Cuadro 26\" src=\"https:\/\/22hbg.com\/wp-content\/uploads\/2026\/02\/Frame-26-1-640x478.jpg\" class=\"attachment-neuros_post_grid_3_columns size-neuros_post_grid_3_columns wp-post-image\" \/><\/picture><\/a><\/div>    <\/div>\n<\/div>\n<div class=\"grid-blog-item-wrapper post-30128 neuros_case_study type-neuros_case_study status-publish has-post-thumbnail hentry neuros_case_study_category-tx-control neuros_case_study_tag-control-tx neuros_case_study_tag-iot-es\">\n    <div class=\"case-study-item\">\n        <h4 class=\"post-title\"><a href=\"https:\/\/22hbg.com\/es\/case-studies\/sala-de-control\/\">Sala de control<\/a><\/h4><div class=\"post-media-wrapper\"><a href=\"https:\/\/22hbg.com\/es\/case-studies\/sala-de-control\/\"><picture><source media=\"(max-width: 575px)\" sizes=\"(max-width: 575px) 575px\" srcset=\"https:\/\/22hbg.com\/wp-content\/uploads\/2025\/08\/Web-1920-\u2013-1-575x274.jpg 575w\"><source media=\"(max-width: 991px)\" sizes=\"(max-width: 991px) 991px\" srcset=\"https:\/\/22hbg.com\/wp-content\/uploads\/2025\/08\/Web-1920-\u2013-1-500x374.jpg 991w\"><img decoding=\"async\" alt=\"Web 1920 - 1\" title=\"Web 1920 - 1\" src=\"https:\/\/22hbg.com\/wp-content\/uploads\/2025\/08\/Web-1920-\u2013-1-640x478.jpg\" class=\"attachment-neuros_post_grid_3_columns size-neuros_post_grid_3_columns wp-post-image\" \/><\/picture><\/a><\/div>    <\/div>\n<\/div>                <\/div>\n\n                <div class=\"content-pagination\"><nav class=\"navigation pagination\" role=\"navigation\"><h2 class=\"screen-reader-text\">Pagination<\/h2><div class=\"nav-links\"><span aria-current=\"page\" class=\"page-numbers current\"><span class=\"button-inner\"><\/span>1<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/22hbg.com\/es\/wp-json\/wp\/v2\/pages\/26537\/?318e44f-paged=2\"><span class=\"button-inner\"><\/span>2<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/22hbg.com\/es\/wp-json\/wp\/v2\/pages\/26537\/?318e44f-paged=3\"><span class=\"button-inner\"><\/span>3<\/a>\n<span class=\"page-numbers dots\">&hellip;<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/22hbg.com\/es\/wp-json\/wp\/v2\/pages\/26537\/?318e44f-paged=5\"><span class=\"button-inner\"><\/span>5<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/22hbg.com\/es\/wp-json\/wp\/v2\/pages\/26537\/?318e44f-paged=6\"><span class=\"button-inner\"><\/span>6<\/a>\n<a class=\"next page-numbers\" href=\"https:\/\/22hbg.com\/es\/wp-json\/wp\/v2\/pages\/26537\/?318e44f-paged=2\">Next<span class=\"button-inner\"><\/span><span class=\"icon-button-arrow left\"><\/span><span class=\"icon-button-arrow right\"><\/span><\/a><\/div><\/nav><\/div>            <\/div>\n\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3698f31 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3698f31\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-0658ea5\" data-id=\"0658ea5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2fe3363 alignment-left icon-position-top elementor-widget elementor-widget-neuros_icon_box\" data-id=\"2fe3363\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"neuros_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"neuros-icon-box-widget\">\n                        <div class=\"icon-box-item\">\n\n                <div class=\"icon-container background-type-none\">\n                    <i class=\"fas fa-brain\"><\/i>                <\/div>\n\n                <div class=\"content-container\">\n                    <h5 class=\"icon-box-title\"><span class=\"neuros-heading-content\">Innovaci\u00f3n aplicada<\/span><\/h5>\n\n                    <div class=\"icon-box-info\"><p data-start=\"1797\" data-end=\"1898\"><strong>La tecnolog\u00eda no nos basta: queremos que sea \u00fatil, medible, real.<\/strong><\/p><p data-start=\"1797\" data-end=\"1898\">Para nosotros, innovar significa transformar la complejidad en herramientas concretas y eficaces. Cada soluci\u00f3n surge de un an\u00e1lisis exhaustivo del contexto, se desarrolla siguiendo una metodolog\u00eda de ingenier\u00eda y se valida sobre el terreno, con m\u00e9tricas claras.<br data-start=\"530\" data-end=\"533\">No seguimos las modas digitales: dise\u00f1amos tecnolog\u00edas que funcionan hoy y crecen ma\u00f1ana. <\/p><\/div>\n                <\/div>\n            <\/div>\n                    <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-689c7c8 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"689c7c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fontello icon-accordion-arrow-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Soluciones a medida para medios de comunicaci\u00f3n y radiodifusi\u00f3n<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fontello icon-accordion-arrow-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Aplicaciones de IA dise\u00f1adas para la productividad<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fontello icon-accordion-arrow-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Software escalable, interconectado y modular<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fontello icon-accordion-arrow-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Plataformas digitales integradas con los sistemas existentes<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fontello icon-accordion-arrow-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Medici\u00f3n del rendimiento en tiempo real<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-052d759\" data-id=\"052d759\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9077086 alignment-left icon-position-top elementor-widget elementor-widget-neuros_icon_box\" data-id=\"9077086\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"neuros_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"neuros-icon-box-widget\">\n                        <div class=\"icon-box-item\">\n\n                <div class=\"icon-container background-type-none\">\n                    <i class=\"fas fa-bolt\"><\/i>                <\/div>\n\n                <div class=\"content-container\">\n                    <h5 class=\"icon-box-title\"><span class=\"neuros-heading-content\">Velocidad y fiabilidad<\/span><\/h5>\n\n                    <div class=\"icon-box-info\"><p data-start=\"935\" data-end=\"1011\"><strong data-start=\"935\" data-end=\"1011\">Desarrollamos soluciones a tiempo, con precisi\u00f3n de ingenier\u00eda.<\/strong><\/p><p data-start=\"1013\" data-end=\"1290\">No prometemos milagros: ofrecemos m\u00e9todo, rigor y rapidez. Nuestro enfoque se basa en el modelo de los \"100 d\u00edas\", dise\u00f1ado para desarrollar soluciones comprobables, fiables y viables en un plazo definido.<br data-start=\"1231\" data-end=\"1234\">Cumplimos los plazos porque respetamos tu tiempo. <\/p><\/div>\n                <\/div>\n            <\/div>\n                    <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bfa6ca5 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"bfa6ca5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fontello icon-accordion-arrow-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Planificaci\u00f3n y hoja de ruta claras<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fontello icon-accordion-arrow-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Desarrollo \u00e1gil con liberaci\u00f3n incremental<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fontello icon-accordion-arrow-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Pruebas continuas y soporte dedicado<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fontello icon-accordion-arrow-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Automatizaci\u00f3n y supervisi\u00f3n activa<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fontello icon-accordion-arrow-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Asistencia y mantenimiento tras la puesta en marcha<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c7823b8\" data-id=\"c7823b8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e3f9033 alignment-left icon-position-top elementor-widget elementor-widget-neuros_icon_box\" data-id=\"e3f9033\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"neuros_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"neuros-icon-box-widget\">\n                        <div class=\"icon-box-item\">\n\n                <div class=\"icon-container background-type-none\">\n                    <i class=\"fas fa-microscope\"><\/i>                <\/div>\n\n                <div class=\"content-container\">\n                    <h5 class=\"icon-box-title\"><span class=\"neuros-heading-content\">Investigaci\u00f3n y desarrollo continuos<\/span><\/h5>\n\n                    <div class=\"icon-box-info\"><p data-start=\"1556\" data-end=\"1626\"><strong data-start=\"1556\" data-end=\"1626\">Invertimos en I+D para anticiparnos a las necesidades del sector tecnol\u00f3gico de los medios de comunicaci\u00f3n.<\/strong><\/p><p data-start=\"1628\" data-end=\"1966\">Nuestro departamento de I+D no es un departamento, sino una forma de pensar. Cada proyecto es una oportunidad para explorar, mejorar y optimizar. Experimentamos con tecnolog\u00edas emergentes y las convertimos en soluciones concretas: desde nuevos algoritmos de compresi\u00f3n de audio hasta interfaces de voz y aplicaciones para Smart TV.<br data-start=\"1907\" data-end=\"1910\">Miramos hacia el futuro, pero con los pies bien plantados en la realidad.  <\/p><\/div>\n                <\/div>\n            <\/div>\n                    <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-465c10c elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"465c10c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fontello icon-accordion-arrow-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Inteligencia Artificial y Automatizaci\u00f3n Editorial<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fontello icon-accordion-arrow-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Protocolos de transmisi\u00f3n innovadores<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fontello icon-accordion-arrow-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Voz y medios sint\u00e9ticos<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fontello icon-accordion-arrow-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">HbbTV, canal FAST y TV conectada<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fontello icon-accordion-arrow-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Nuevas normas para la radiodifusi\u00f3n digital<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-80fe36e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"80fe36e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-bbddadb\" data-id=\"bbddadb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-20c7283 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"20c7283\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-35b9dd5\" data-id=\"35b9dd5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f85f89d elementor-widget elementor-widget-neuros_heading\" data-id=\"f85f89d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"neuros_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"neuros-heading-widget\"><h2 class=\"neuros-heading\"><span class=\"neuros-subheading\">ponte en contacto<\/span><span class=\"neuros-heading-content has_gradient_color_text\">Siempre estamos dispuestos a ayudarte y a responder a tus preguntas.   <\/span><\/h2><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-612eb22 elementor-widget elementor-widget-text-editor\" data-id=\"612eb22\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"366\" data-end=\"424\">Un mensaje es el principio de toda gran colaboraci\u00f3n.<\/p><p data-start=\"426\" data-end=\"503\" data-is-last-node=\"\" data-is-only-node=\"\"> <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3ff4b2a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3ff4b2a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2d46c6e\" data-id=\"2d46c6e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7cfbfad elementor-widget elementor-widget-neuros_heading\" data-id=\"7cfbfad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"neuros_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"neuros-heading-widget\"><h6 class=\"neuros-heading\"><span class=\"neuros-heading-content has_gradient_color_text\">Tel\u00e9fono<\/span><\/h6><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a0327be elementor-widget elementor-widget-text-editor\" data-id=\"a0327be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"tel:0532%201914%20149\">0532 1914 149<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d8f5940 elementor-widget elementor-widget-neuros_heading\" data-id=\"d8f5940\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"neuros_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"neuros-heading-widget\"><h6 class=\"neuros-heading\"><span class=\"neuros-heading-content has_gradient_color_text\">Env\u00eda un correo electr\u00f3nico a<\/span><\/h6><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-004c1af elementor-widget elementor-widget-text-editor\" data-id=\"004c1af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"mailto:info@22hbg.com\">info@22hbg.com<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8e9dbaa\" data-id=\"8e9dbaa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cd58048 elementor-widget elementor-widget-neuros_heading\" data-id=\"cd58048\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"neuros_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"neuros-heading-widget\"><h6 class=\"neuros-heading\"><span class=\"neuros-heading-content has_gradient_color_text\">D\u00f3nde encontrarnos<\/span><\/h6><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62ea5a4 elementor-widget elementor-widget-text-editor\" data-id=\"62ea5a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/maps.app.goo.gl\/jXv4wy4Wv8SoKbqt9\">Via Modena 119, Ferrara.<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0367655 elementor-widget elementor-widget-neuros_heading\" data-id=\"0367655\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"neuros_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"neuros-heading-widget\"><h6 class=\"neuros-heading\"><span class=\"neuros-heading-content has_gradient_color_text\">Redes sociales<\/span><\/h6><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9d4c7df elementor-shape-square e-grid-align-left elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"9d4c7df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook-f elementor-repeater-item-e9738af\" href=\"https:\/\/www.facebook.com\/22HBG\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook-f<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook-f\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-linkedin-in elementor-repeater-item-0770189\" href=\"https:\/\/www.linkedin.com\/company\/22hbg\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Linkedin-in<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-linkedin-in\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-5350dac\" href=\"https:\/\/www.instagram.com\/22hbg\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ee7ee2e\" data-id=\"ee7ee2e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d74ed34 wpforms-button-border-style-solid wpforms-button-bakground-style-solid elementor-widget elementor-widget-neuros_wpforms\" data-id=\"d74ed34\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"neuros_wpforms.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"neuros-wpforms-widget\">\n            <h4 class=\"wpforms-widget-heading neuros-heading\"><span class=\"neuros-heading-content\">Ponte en contacto<\/span><\/h4><style id=\"wpforms-css-vars-23200\">\n\t\t\t\t#wpforms-23200 {\n\t\t\t\t--wpforms-container-padding: 0px;\n--wpforms-container-border-width: 1px;\n--wpforms-container-border-radius: 3px;\n--wpforms-background-color: rgba(0, 0, 0, 0);\n--wpforms-field-size-input-height: 43px;\n--wpforms-field-size-input-spacing: 15px;\n--wpforms-field-size-font-size: 16px;\n--wpforms-field-size-line-height: 19px;\n--wpforms-field-size-padding-h: 14px;\n--wpforms-field-size-checkbox-size: 16px;\n--wpforms-field-size-sublabel-spacing: 5px;\n--wpforms-field-size-icon-size: 1;\n--wpforms-label-size-font-size: 16px;\n--wpforms-label-size-line-height: 19px;\n--wpforms-label-size-sublabel-font-size: 14px;\n--wpforms-label-size-sublabel-line-height: 17px;\n--wpforms-button-size-font-size: 17px;\n--wpforms-button-size-height: 41px;\n--wpforms-button-size-padding-h: 15px;\n--wpforms-button-size-margin-top: 10px;\n--wpforms-container-shadow-size-box-shadow: none;\n\t\t\t}\n\t\t\t<\/style><div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-23200\"><form id=\"wpforms-form-23200\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"23200\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/es\/wp-json\/wp\/v2\/pages\/26537\" data-token=\"0777fc985ced5bbc55ce24e654c9ad4d\" data-token-time=\"1778704213\"><div class=\"wpforms-head-container\"><div class=\"wpforms-description\">Ogni grande progetto nasce da un buon ascolto.<\/div><\/div><noscript class=\"wpforms-error-noscript\">Por favor, activa JavaScript en tu navegador para completar este formulario.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Por favor, activa JavaScript en tu navegador para completar este formulario.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-23200-field_1-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"1\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-23200-field_1\" aria-hidden=\"false\">Nome <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-23200-field_1\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][1]\" placeholder=\"Nome\" aria-errormessage=\"wpforms-23200-field_1-error\" required><\/div><div id=\"wpforms-23200-field_3-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"3\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-23200-field_3\" aria-hidden=\"false\">Email <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-23200-field_3\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][3]\" placeholder=\"Email\" spellcheck=\"false\" aria-errormessage=\"wpforms-23200-field_3-error\" required><\/div><div id=\"wpforms-23200-field_4-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"4\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-23200-field_4\" aria-hidden=\"false\">Oggetto <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-23200-field_4\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][4]\" placeholder=\"Oggetto\" aria-errormessage=\"wpforms-23200-field_4-error\" required><\/div>\t\t<div id=\"wpforms-23200-field_2-container\"\n\t\t\tclass=\"wpforms-field wpforms-field-text\"\n\t\t\tdata-field-type=\"text\"\n\t\t\tdata-field-id=\"2\"\n\t\t\t>\n\t\t\t<label class=\"wpforms-field-label\" for=\"wpforms-23200-field_2\" >Nome Oggetto Messaggio<\/label>\n\t\t\t<input type=\"text\" id=\"wpforms-23200-field_2\" class=\"wpforms-field-medium\" name=\"wpforms[fields][2]\" >\n\t\t<\/div>\n\t\t<div id=\"wpforms-23200-field_5-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"5\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-23200-field_5\" aria-hidden=\"false\">Messaggio<\/label><textarea id=\"wpforms-23200-field_5\" class=\"wpforms-field-small\" name=\"wpforms[fields][5]\" placeholder=\"Messaggio\" aria-errormessage=\"wpforms-23200-field_5-error\" ><\/textarea><\/div><script>\n\t\t\t\t( function() {\n\t\t\t\t\tconst style = document.createElement( 'style' );\n\t\t\t\t\tstyle.appendChild( document.createTextNode( '#wpforms-23200-field_2-container { position: absolute !important; overflow: hidden !important; display: inline !important; height: 1px !important; width: 1px !important; z-index: -1000 !important; padding: 0 !important; } #wpforms-23200-field_2-container input { visibility: hidden; } #wpforms-conversational-form-page #wpforms-23200-field_2-container label { counter-increment: none; }' ) );\n\t\t\t\t\tdocument.head.appendChild( style );\n\t\t\t\t\tdocument.currentScript?.remove();\n\t\t\t\t} )();\n\t\t\t<\/script><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"23200\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/22hbg.com\/es\/wp-json\/wp\/v2\/pages\/26537\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-23200\" class=\"wpforms-submit\" data-alt-text=\"Invio...\" data-submit-text=\"Invia\" aria-live=\"assertive\" value=\"wpforms-submit\">Invia<\/button><img decoding=\"async\" src=\"https:\/\/22hbg.com\/wp-content\/plugins\/wpforms-lite\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Cargando\"><\/div><\/form><\/div>  <!-- .wpforms-container -->        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8a71309 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8a71309\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d45eb0d\" data-id=\"d45eb0d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9f5b55d\" data-id=\"9f5b55d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2014284 elementor-widget__width-initial elementor-widget elementor-widget-neuros_heading\" data-id=\"2014284\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"neuros_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"neuros-heading-widget\"><h2 class=\"neuros-heading\"><span class=\"neuros-subheading\">nuestra historia<\/span><span class=\"neuros-heading-content has_gradient_color_text\">Pasado. Presente.Futuro. <\/span><\/h2><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-93d02a5 elementor-widget elementor-widget-neuros_awards\" data-id=\"93d02a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"neuros_awards.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"neuros-awards-widget\">\n            <div class=\"awards-list\">\n                                    <div class=\"award-item\">\n                        <div class=\"award-year-column\">\n                            <span class=\"award-year\">2011<\/span>                        <\/div>\n                        <div class=\"award-subtitle-column\">\n                            <span class=\"award-subtitle\">Fundaci\u00f3n<\/span>                        <\/div>\n                        <div class=\"award-title-column\">\n                            <h4 class=\"award-title\"><span>Fundaci\u00f3n en Italia, con la ambici\u00f3n de innovar la radiodifusi\u00f3n digital.<\/span>\n<\/h4>                        <\/div>\n                    <\/div>\n                                        <div class=\"award-item\">\n                        <div class=\"award-year-column\">\n                            <span class=\"award-year\">2012\u20132014<\/span>                        <\/div>\n                        <div class=\"award-subtitle-column\">\n                            <span class=\"award-subtitle\">FM-world<\/span>                        <\/div>\n                        <div class=\"award-title-column\">\n                            <h4 class=\"award-title\"><span>Desarrollo de FM\u2011World, agregador de radios digitales en streaming.<\/span>\n<\/h4>                        <\/div>\n                    <\/div>\n                                        <div class=\"award-item\">\n                        <div class=\"award-year-column\">\n                            <span class=\"award-year\">2015\u20132016<\/span>                        <\/div>\n                        <div class=\"award-subtitle-column\">\n                            <span class=\"award-subtitle\">App mobile<\/span>                        <\/div>\n                        <div class=\"award-title-column\">\n                            <h4 class=\"award-title\"><span>Creaci\u00f3n de aplicaciones m\u00f3viles y primeras soluciones vocales inteligentes.<\/span>\n<\/h4>                        <\/div>\n                    <\/div>\n                                        <div class=\"award-item\">\n                        <div class=\"award-year-column\">\n                            <span class=\"award-year\">2017\u20132018<\/span>                        <\/div>\n                        <div class=\"award-subtitle-column\">\n                            <span class=\"award-subtitle\">Peperoni<\/span>                        <\/div>\n                        <div class=\"award-title-column\">\n                            <h4 class=\"award-title\"><span>Lanzamiento de Peperoni, plataforma para contenidos multicanal.<\/span>\n<\/h4>                        <\/div>\n                    <\/div>\n                                        <div class=\"award-item\">\n                        <div class=\"award-year-column\">\n                            <span class=\"award-year\">2019<\/span>                        <\/div>\n                        <div class=\"award-subtitle-column\">\n                            <span class=\"award-subtitle\">International<\/span>                        <\/div>\n                        <div class=\"award-title-column\">\n                            <h4 class=\"award-title\"><span>Apertura de la sede en <strong>Dakar<\/strong>; expansi\u00f3n en \u00c1frica en los medios de comunicaci\u00f3n y los servicios p\u00fablicos.<\/span>\n<\/h4>                        <\/div>\n                    <\/div>\n                                        <div class=\"award-item\">\n                        <div class=\"award-year-column\">\n                            <span class=\"award-year\">2020\u20132021<\/span>                        <\/div>\n                        <div class=\"award-subtitle-column\">\n                            <span class=\"award-subtitle\">Smart city<\/span>                        <\/div>\n                        <div class=\"award-title-column\">\n                            <h4 class=\"award-title\"><span>Proyectos para ciudades inteligentes, distritos urbanos y comercio electr\u00f3nico territorial.<\/span>\n<\/h4>                        <\/div>\n                    <\/div>\n                                        <div class=\"award-item\">\n                        <div class=\"award-year-column\">\n                            <span class=\"award-year\">2022<\/span>                        <\/div>\n                        <div class=\"award-subtitle-column\">\n                            <span class=\"award-subtitle\">TX Control<\/span>                        <\/div>\n                        <div class=\"award-title-column\">\n                            <h4 class=\"award-title\"><span>Amplia adopci\u00f3n de <strong>TX Control <\/strong>para la gesti\u00f3n y supervisi\u00f3n remotas.<\/span>\n<\/h4>                        <\/div>\n                    <\/div>\n                                        <div class=\"award-item\">\n                        <div class=\"award-year-column\">\n                            <span class=\"award-year\">2023<\/span>                        <\/div>\n                        <div class=\"award-subtitle-column\">\n                            <span class=\"award-subtitle\">IA<\/span>                        <\/div>\n                        <div class=\"award-title-column\">\n                            <h4 class=\"award-title\">Introducci\u00f3n de la generaci\u00f3n autom\u00e1tica de audio basada en IA.\n<\/h4>                        <\/div>\n                    <\/div>\n                                        <div class=\"award-item\">\n                        <div class=\"award-year-column\">\n                            <span class=\"award-year\">2024<\/span>                        <\/div>\n                        <div class=\"award-subtitle-column\">\n                            <span class=\"award-subtitle\">Asesoramiento<\/span>                        <\/div>\n                        <div class=\"award-title-column\">\n                            <h4 class=\"award-title\"><span>Reconocimiento en <strong>consultor\u00eda estrat\u00e9gica<\/strong> tecnol\u00f3gica para grupos de radiodifusi\u00f3n, colaborando con l\u00edderes del sector.<\/span>\n<\/h4>                        <\/div>\n                    <\/div>\n                                        <div class=\"award-item\">\n                        <div class=\"award-year-column\">\n                            <span class=\"award-year\">2025<\/span>                        <\/div>\n                        <div class=\"award-subtitle-column\">\n                            <span class=\"award-subtitle\">Samsung y FAST channel<\/span>                        <\/div>\n                        <div class=\"award-title-column\">\n                            <h4 class=\"award-title\">Alianzas estrat\u00e9gicas con <strong>Samsung y Amagi<\/strong> para Fast Channel en Smart TV y OTT.\n<\/h4>                        <\/div>\n                    <\/div>\n                                <\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Somos una empresa tecnol\u00f3gica italiana que desarrolla soluciones de software y sistemas digitales para medios de comunicaci\u00f3n, radiodifusi\u00f3n y tecnolog\u00edas inteligentes. Cada proyecto nace de un an\u00e1lisis concreto y se traduce en una tecnolog\u00eda escalable, sostenible y de gran impacto. Para&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-26537","page","type-page","status-publish","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/22hbg.com\/es\/wp-json\/wp\/v2\/pages\/26537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/22hbg.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/22hbg.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/22hbg.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/22hbg.com\/es\/wp-json\/wp\/v2\/comments?post=26537"}],"version-history":[{"count":3,"href":"https:\/\/22hbg.com\/es\/wp-json\/wp\/v2\/pages\/26537\/revisions"}],"predecessor-version":[{"id":27024,"href":"https:\/\/22hbg.com\/es\/wp-json\/wp\/v2\/pages\/26537\/revisions\/27024"}],"wp:attachment":[{"href":"https:\/\/22hbg.com\/es\/wp-json\/wp\/v2\/media?parent=26537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}