{"id":26659,"date":"2025-07-10T16:44:10","date_gmt":"2025-07-10T15:44:10","guid":{"rendered":"https:\/\/22hbg.com\/leducation\/"},"modified":"2025-12-15T11:32:49","modified_gmt":"2025-12-15T10:32:49","slug":"leducation","status":"publish","type":"page","link":"https:\/\/22hbg.com\/fr\/leducation\/","title":{"rendered":"L&rsquo;\u00e9ducation"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"26659\" class=\"elementor elementor-26659 elementor-25371\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-59982b1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"59982b1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1cbfcaa\" data-id=\"1cbfcaa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1d33f36 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1d33f36\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-0f4e302\" data-id=\"0f4e302\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5cbb406 neuros-icon-alignment-left elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"5cbb406\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-user-graduate\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b533a80 elementor-widget elementor-widget-text-editor\" data-id=\"b533a80\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4 data-start=\"615\" data-end=\"658\">Pourquoi l&rsquo;\u00e9ducation dans le monde de la technologie ?<\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-fda9ab4\" data-id=\"fda9ab4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9420f15 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"9420f15\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"659\" data-end=\"912\">Dans un secteur o\u00f9 l&rsquo;innovation est rapide, rester \u00e0 jour n&rsquo;est pas un avantage : c&rsquo;est une n\u00e9cessit\u00e9.<br data-start=\"763\" data-end=\"766\">C&rsquo;est pourquoi nous avons transform\u00e9 notre exp\u00e9rience en un cours de formation destin\u00e9 \u00e0 ceux qui veulent comprendre, planifier et conduire le changement.<\/p><p data-start=\"914\" data-end=\"1142\">De la formation interne aux ateliers en classe, des webinaires th\u00e9matiques aux cours sur l&rsquo;IA, HbbTV et FAST Channel, nous accompagnons les <a href=\"https:\/\/22hbg.com\/peperoni-cms\/\">entreprises de m\u00e9dias<\/a>, les <a href=\"https:\/\/22hbg.com\/fm-world\/\">diffuseurs<\/a> et les <a href=\"https:\/\/22hbg.com\/tx-control\/\">professionnels<\/a> vers une approche inform\u00e9e et strat\u00e9gique de la technologie.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-71185b6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"71185b6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-199e6e5\" data-id=\"199e6e5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f2859ce elementor-widget elementor-widget-neuros_services_listing\" data-id=\"f2859ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"neuros_services_listing.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"neuros-service-listing-widget\">\n                        \n            <div class=\"archive-listing\" data-ajax='{&quot;post_type&quot;:&quot;neuros_service&quot;,&quot;ignore_sticky_posts&quot;:true,&quot;orderby&quot;:&quot;date&quot;,&quot;order&quot;:&quot;desc&quot;,&quot;link_base&quot;:&quot;https:\\\/\\\/22hbg.com\\\/fr\\\/wp-json\\\/wp\\\/v2\\\/pages\\\/26659\\\/&quot;,&quot;post__in&quot;:[&quot;27916&quot;],&quot;posts_per_page&quot;:4,&quot;paged&quot;:1}' data-widget='{&quot;listing_type&quot;:&quot;list&quot;,&quot;item_class&quot;:&quot;service-item-wrapper&quot;,&quot;show_pagination&quot;:&quot;&quot;}'>\n                <div class=\"archive-listing-wrapper service-listing-wrapper service-list-listing\">\n                                    <\/div>\n\n                            <\/div>\n\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-76c3bde elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"76c3bde\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9856c2b\" data-id=\"9856c2b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a2b7cf neuros-button-border-style-gradient neuros-button-bakground-style-solid elementor-widget elementor-widget-neuros_price_item\" data-id=\"1a2b7cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"neuros_price_item.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"neuros-price-item-widget\">\n            <div class=\"price-item price-item-type-standard\">\n                \n                <div class=\"price-item-label-wrapper\"><div class=\"price-item-label\">Formation sp\u00e9cialis\u00e9e<\/div><\/div>                <div class=\"price-item-inner\">\n\n                    <div class=\"price-item-title\">Formation en entreprise<\/div><div class=\"price-item-description\">Creamos programas de formaci\u00f3n a medida para empresas que desean integrar nuevas tecnolog\u00edas en su flujo de trabajo. Desde la inteligencia artificial aplicada a los medios de comunicaci\u00f3n, pasando por la optimizaci\u00f3n de procesos con soluciones avanzadas de software\/hardware, hasta la supervisi\u00f3n remota de sistemas con TX Control. Cada programa se adapta al nivel, los objetivos y los equipos implicados.  <\/div>                        <div class=\"price-item-custom-fields\">\n                                                    <\/div>\n                                                <div class=\"price-item-container price-item-currency-position-before\">\n                            <div class=\"price-wrapper\">\n                                <span class=\"price\"><\/span>                            <\/div>\n\n                                                    <\/div>\n                        \n                                    <\/div>\n            <\/div>\n                    <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-957b34b neuros-button-border-style-gradient neuros-button-bakground-style-solid elementor-widget elementor-widget-neuros_price_item\" data-id=\"957b34b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"neuros_price_item.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"neuros-price-item-widget\">\n            <div class=\"price-item price-item-type-standard\">\n                \n                <div class=\"price-item-label-wrapper\"><div class=\"price-item-label\">Technologie didactique<\/div><\/div>                <div class=\"price-item-inner\">\n\n                    <div class=\"price-item-title\">Ateliers pour les universit\u00e9s<\/div><div class=\"price-item-description\">Nous collaborons avec des \u00e9coles et des universit\u00e9s pour int\u00e9grer notre expertise en mati\u00e8re de radiodiffusion, d&#039;exp\u00e9rience utilisateur et de num\u00e9risation des flux m\u00e9diatiques dans le programme d&#039;\u00e9tudes. Nos ateliers combinent th\u00e9orie et pratique, avec des conf\u00e9renciers experts et des cas r\u00e9els issus de notre travail quotidien. <\/div>                        <div class=\"price-item-custom-fields\">\n                                                    <\/div>\n                                                <div class=\"price-item-container price-item-currency-position-before\">\n                            <div class=\"price-wrapper\">\n                                <span class=\"price\"><\/span>                            <\/div>\n\n                                                    <\/div>\n                        \n                                    <\/div>\n            <\/div>\n                    <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-eed88c0\" data-id=\"eed88c0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2dda1ce elementor-widget-laptop__width-initial neuros-button-border-style-gradient neuros-button-bakground-style-solid elementor-widget elementor-widget-neuros_price_item\" data-id=\"2dda1ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"neuros_price_item.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"neuros-price-item-widget\">\n            <div class=\"price-item price-item-type-standard\">\n                \n                <div class=\"price-item-label-wrapper\"><div class=\"price-item-label\">\u00c9v\u00e9nements en ligne<\/div><\/div>                <div class=\"price-item-inner\">\n\n                    <div class=\"price-item-title\">Webinaires et masterclasses<\/div><div class=\"price-item-description\">Nous organisons des r\u00e9unions num\u00e9riques pour explorer les innovations qui transforment le monde des m\u00e9dias. Nous abordons des sujets tels que la Smart TV et la HbbTV, la distribution OTT via FAST Channel et les strat\u00e9gies avanc\u00e9es de mon\u00e9tisation num\u00e9rique. Les sessions sont en direct ou \u00e0 la demande, con\u00e7ues pour les professionnels \u00e0 la recherche de mises \u00e0 jour continues.  <\/div>                        <div class=\"price-item-custom-fields\">\n                                                    <\/div>\n                                                <div class=\"price-item-container price-item-currency-position-before\">\n                            <div class=\"price-wrapper\">\n                                <span class=\"price\"><\/span>                            <\/div>\n\n                                                    <\/div>\n                        \n                                    <\/div>\n            <\/div>\n                    <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-75180c5 neuros-button-border-style-gradient neuros-button-bakground-style-solid elementor-widget elementor-widget-neuros_price_item\" data-id=\"75180c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"neuros_price_item.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"neuros-price-item-widget\">\n            <div class=\"price-item price-item-type-standard\">\n                \n                <div class=\"price-item-label-wrapper\"><div class=\"price-item-label\">Soutien op\u00e9rationnel<\/div><\/div>                <div class=\"price-item-inner\">\n\n                    <div class=\"price-item-title\">Onboarding technique<\/div><div class=\"price-item-description\">Cada soluci\u00f3n firmada por 22HBG incluye un proceso de incorporaci\u00f3n dise\u00f1ado para garantizar la autonom\u00eda y el conocimiento. Ofrecemos sesiones t\u00e9cnicas, tutoriales, documentaci\u00f3n y asistencia en directo para plataformas como TX Control, HbbTV o sistemas FAST. Nuestro objetivo es transmitir no solo el funcionamiento, sino tambi\u00e9n el valor estrat\u00e9gico de las tecnolog\u00edas adoptadas.  \n<\/div>                        <div class=\"price-item-custom-fields\">\n                                                    <\/div>\n                                                <div class=\"price-item-container price-item-currency-position-before\">\n                            <div class=\"price-wrapper\">\n                                <span class=\"price\"><\/span>                            <\/div>\n\n                                                    <\/div>\n                        \n                                    <\/div>\n            <\/div>\n                    <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9992fd7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9992fd7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-91b2c8f\" data-id=\"91b2c8f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8463131 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8463131\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-ed853df\" data-id=\"ed853df\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-910f3bf elementor-widget elementor-widget-neuros_heading\" data-id=\"910f3bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"neuros_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"neuros-heading-widget\"><h2 class=\"neuros-heading\"><span class=\"neuros-subheading\">Prenez contact avec nous<\/span><span class=\"neuros-heading-content has_gradient_color_text\">Nous sommes toujours pr\u00eats \u00e0 vous aider et \u00e0 r\u00e9pondre \u00e0 vos questions.   <\/span><\/h2><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73b80a1 elementor-widget elementor-widget-text-editor\" data-id=\"73b80a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"366\" data-end=\"424\">Un message est le point de d\u00e9part de toute grande collaboration.<\/p><p data-start=\"426\" data-end=\"503\" data-is-last-node=\"\" data-is-only-node=\"\"> <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-dfcbf87 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dfcbf87\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1f198b6\" data-id=\"1f198b6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7ca4e97 elementor-widget elementor-widget-neuros_heading\" data-id=\"7ca4e97\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"neuros_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"neuros-heading-widget\"><h6 class=\"neuros-heading\"><span class=\"neuros-heading-content has_gradient_color_text\">T\u00e9l\u00e9phone<\/span><\/h6><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ff3ac1 elementor-widget elementor-widget-text-editor\" data-id=\"6ff3ac1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"tel:0532%201914%20149\">0532 1914 149<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-590f089 elementor-widget elementor-widget-neuros_heading\" data-id=\"590f089\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"neuros_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"neuros-heading-widget\"><h6 class=\"neuros-heading\"><span class=\"neuros-heading-content has_gradient_color_text\">Courriel<\/span><\/h6><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0a589c7 elementor-widget elementor-widget-text-editor\" data-id=\"0a589c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"mailto:info@22hbg.com\">info@22hbg.com<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4c63d83\" data-id=\"4c63d83\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-23b308c elementor-widget elementor-widget-neuros_heading\" data-id=\"23b308c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"neuros_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"neuros-heading-widget\"><h6 class=\"neuros-heading\"><span class=\"neuros-heading-content has_gradient_color_text\">O\u00f9 nous trouver<\/span><\/h6><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a958098 elementor-widget elementor-widget-text-editor\" data-id=\"a958098\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/maps.app.goo.gl\/jXv4wy4Wv8SoKbqt9\">Via Modena 119, Ferrara.<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ad57824 elementor-widget elementor-widget-neuros_heading\" data-id=\"ad57824\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"neuros_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"neuros-heading-widget\"><h6 class=\"neuros-heading\"><span class=\"neuros-heading-content has_gradient_color_text\">R\u00e9seaux sociaux<\/span><\/h6><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f916ad elementor-shape-square e-grid-align-left elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"6f916ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook-f elementor-repeater-item-e9738af\" href=\"https:\/\/www.facebook.com\/22HBG\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook-f<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook-f\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-linkedin-in elementor-repeater-item-0770189\" href=\"https:\/\/www.linkedin.com\/company\/22hbg\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Linkedin-in<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-linkedin-in\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-5350dac\" href=\"https:\/\/www.instagram.com\/22hbg\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-34ff39e\" data-id=\"34ff39e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-62934a2 wpforms-button-border-style-solid wpforms-button-bakground-style-solid elementor-widget elementor-widget-neuros_wpforms\" data-id=\"62934a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"neuros_wpforms.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"neuros-wpforms-widget\">\n            <h4 class=\"wpforms-widget-heading neuros-heading\"><span class=\"neuros-heading-content\">Prenez contact avec nous<\/span><\/h4><style id=\"wpforms-css-vars-23200\">\n\t\t\t\t#wpforms-23200 {\n\t\t\t\t--wpforms-container-padding: 0px;\n--wpforms-container-border-width: 1px;\n--wpforms-container-border-radius: 3px;\n--wpforms-background-color: rgba(0, 0, 0, 0);\n--wpforms-field-size-input-height: 43px;\n--wpforms-field-size-input-spacing: 15px;\n--wpforms-field-size-font-size: 16px;\n--wpforms-field-size-line-height: 19px;\n--wpforms-field-size-padding-h: 14px;\n--wpforms-field-size-checkbox-size: 16px;\n--wpforms-field-size-sublabel-spacing: 5px;\n--wpforms-field-size-icon-size: 1;\n--wpforms-label-size-font-size: 16px;\n--wpforms-label-size-line-height: 19px;\n--wpforms-label-size-sublabel-font-size: 14px;\n--wpforms-label-size-sublabel-line-height: 17px;\n--wpforms-button-size-font-size: 17px;\n--wpforms-button-size-height: 41px;\n--wpforms-button-size-padding-h: 15px;\n--wpforms-button-size-margin-top: 10px;\n--wpforms-container-shadow-size-box-shadow: none;\n\t\t\t}\n\t\t\t<\/style><div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-23200\"><form id=\"wpforms-form-23200\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"23200\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/fr\/wp-json\/wp\/v2\/pages\/26659\" data-token=\"98277cea23e155f0b92729ddea6202ee\" data-token-time=\"1784091547\"><div class=\"wpforms-head-container\"><div class=\"wpforms-description\">Ogni grande progetto nasce da un buon ascolto.<\/div><\/div><noscript class=\"wpforms-error-noscript\">Veuillez activer JavaScript dans votre navigateur pour remplir ce formulaire.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Veuillez activer JavaScript dans votre navigateur pour remplir ce formulaire.<\/div><div class=\"wpforms-field-container\">\t\t<div id=\"wpforms-23200-field_2-container\"\n\t\t\tclass=\"wpforms-field wpforms-field-text\"\n\t\t\tdata-field-type=\"text\"\n\t\t\tdata-field-id=\"2\"\n\t\t\t>\n\t\t\t<label class=\"wpforms-field-label\" for=\"wpforms-23200-field_2\" >Nome Oggetto Email<\/label>\n\t\t\t<input type=\"text\" id=\"wpforms-23200-field_2\" class=\"wpforms-field-medium\" name=\"wpforms[fields][2]\" >\n\t\t<\/div>\n\t\t<div id=\"wpforms-23200-field_1-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"1\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-23200-field_1\" aria-hidden=\"false\">Nome <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-23200-field_1\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][1]\" placeholder=\"Nome\" aria-errormessage=\"wpforms-23200-field_1-error\" required><\/div><div id=\"wpforms-23200-field_3-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"3\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-23200-field_3\" aria-hidden=\"false\">Email <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-23200-field_3\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][3]\" placeholder=\"Email\" spellcheck=\"false\" aria-errormessage=\"wpforms-23200-field_3-error\" required><\/div><div id=\"wpforms-23200-field_4-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"4\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-23200-field_4\" aria-hidden=\"false\">Oggetto <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-23200-field_4\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][4]\" placeholder=\"Oggetto\" aria-errormessage=\"wpforms-23200-field_4-error\" required><\/div><div id=\"wpforms-23200-field_5-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"5\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-23200-field_5\" aria-hidden=\"false\">Messaggio<\/label><textarea id=\"wpforms-23200-field_5\" class=\"wpforms-field-small\" name=\"wpforms[fields][5]\" placeholder=\"Messaggio\" aria-errormessage=\"wpforms-23200-field_5-error\" ><\/textarea><\/div><script>\n\t\t\t\t( function() {\n\t\t\t\t\tconst style = document.createElement( 'style' );\n\t\t\t\t\tstyle.appendChild( document.createTextNode( '#wpforms-23200-field_2-container { position: absolute !important; overflow: hidden !important; display: inline !important; height: 1px !important; width: 1px !important; z-index: -1000 !important; padding: 0 !important; } #wpforms-23200-field_2-container input { visibility: hidden; } #wpforms-conversational-form-page #wpforms-23200-field_2-container label { counter-increment: none; }' ) );\n\t\t\t\t\tdocument.head.appendChild( style );\n\t\t\t\t\tdocument.currentScript?.remove();\n\t\t\t\t} )();\n\t\t\t<\/script><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"23200\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/22hbg.com\/fr\/wp-json\/wp\/v2\/pages\/26659\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-23200\" class=\"wpforms-submit\" data-alt-text=\"Invio...\" data-submit-text=\"Invia\" aria-live=\"assertive\" value=\"wpforms-submit\">Invia<\/button><img decoding=\"async\" src=\"https:\/\/22hbg.com\/wp-content\/plugins\/wpforms-lite\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Chargement en cours\"><\/div><\/form><\/div>  <!-- .wpforms-container -->        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Pourquoi l&rsquo;\u00e9ducation dans le monde de la technologie ? Dans un secteur o\u00f9 l&rsquo;innovation est rapide, rester \u00e0 jour n&rsquo;est pas un avantage : c&rsquo;est une n\u00e9cessit\u00e9.C&rsquo;est pourquoi nous avons transform\u00e9 notre exp\u00e9rience en un cours de formation destin\u00e9 \u00e0 ceux&#8230;<\/p>\n","protected":false},"author":1,"featured_media":24936,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-26659","page","type-page","status-publish","has-post-thumbnail","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Pourquoi l\u2019\u00e9ducation dans le monde de la technologie ? Dans un secteur o\u00f9 l\u2019innovation est rapide, rester \u00e0 jour n\u2019est pas un avantage : c\u2019est une n\u00e9cessit\u00e9.C\u2019est pourquoi nous avons transform\u00e9 notre exp\u00e9rience en un cours de formation destin\u00e9 \u00e0 ceux qui veulent comprendre, planifier et conduire le changement.De la formation interne aux ateliers en\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"google-site-verification\" content=\"mzzECBsCyHPEXBD4J7fk6YS6Kxma137XTchmt2Vyijg\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/22hbg.com\/fr\/leducation\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"22HBG - Powering the future\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"L\u2019\u00e9ducation - 22HBG\" \/>\n\t\t<meta property=\"og:description\" content=\"Pourquoi l\u2019\u00e9ducation dans le monde de la technologie ? Dans un secteur o\u00f9 l\u2019innovation est rapide, rester \u00e0 jour n\u2019est pas un avantage : c\u2019est une n\u00e9cessit\u00e9.C\u2019est pourquoi nous avons transform\u00e9 notre exp\u00e9rience en un cours de formation destin\u00e9 \u00e0 ceux qui veulent comprendre, planifier et conduire le changement.De la formation interne aux ateliers en\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/22hbg.com\/fr\/leducation\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-07-10T15:44:10+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-12-15T10:32:49+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"L\u2019\u00e9ducation - 22HBG\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Pourquoi l\u2019\u00e9ducation dans le monde de la technologie ? Dans un secteur o\u00f9 l\u2019innovation est rapide, rester \u00e0 jour n\u2019est pas un avantage : c\u2019est une n\u00e9cessit\u00e9.C\u2019est pourquoi nous avons transform\u00e9 notre exp\u00e9rience en un cours de formation destin\u00e9 \u00e0 ceux qui veulent comprendre, planifier et conduire le changement.De la formation interne aux ateliers en\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/22hbg.com\\\/fr\\\/leducation\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/22hbg.com\\\/fr\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/22hbg.com\\\/fr\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/22hbg.com\\\/fr\\\/leducation\\\/#listItem\",\"name\":\"L&rsquo;\\u00e9ducation\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/22hbg.com\\\/fr\\\/leducation\\\/#listItem\",\"position\":2,\"name\":\"L&rsquo;\\u00e9ducation\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/22hbg.com\\\/fr\\\/#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/22hbg.com\\\/fr\\\/#organization\",\"name\":\"22HBG\",\"description\":\"Powering the future\",\"url\":\"https:\\\/\\\/22hbg.com\\\/fr\\\/\",\"email\":\"info@22hbg.com\",\"telephone\":\"+393317316391\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/22hbg.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/22hbg_favicon_logo.png\",\"@id\":\"https:\\\/\\\/22hbg.com\\\/fr\\\/leducation\\\/#organizationLogo\",\"width\":512,\"height\":512,\"caption\":\"22HBG\"},\"image\":{\"@id\":\"https:\\\/\\\/22hbg.com\\\/fr\\\/leducation\\\/#organizationLogo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/22hbg.com\\\/fr\\\/leducation\\\/#webpage\",\"url\":\"https:\\\/\\\/22hbg.com\\\/fr\\\/leducation\\\/\",\"name\":\"L\\u2019\\u00e9ducation - 22HBG\",\"description\":\"Pourquoi l\\u2019\\u00e9ducation dans le monde de la technologie ? Dans un secteur o\\u00f9 l\\u2019innovation est rapide, rester \\u00e0 jour n\\u2019est pas un avantage : c\\u2019est une n\\u00e9cessit\\u00e9.C\\u2019est pourquoi nous avons transform\\u00e9 notre exp\\u00e9rience en un cours de formation destin\\u00e9 \\u00e0 ceux qui veulent comprendre, planifier et conduire le changement.De la formation interne aux ateliers en\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/22hbg.com\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/22hbg.com\\\/fr\\\/leducation\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/22hbg.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/tx-control-card-bg.webp\",\"@id\":\"https:\\\/\\\/22hbg.com\\\/fr\\\/leducation\\\/#mainImage\",\"width\":400,\"height\":600},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/22hbg.com\\\/fr\\\/leducation\\\/#mainImage\"},\"datePublished\":\"2025-07-10T16:44:10+01:00\",\"dateModified\":\"2025-12-15T11:32:49+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/22hbg.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/22hbg.com\\\/fr\\\/\",\"name\":\"22HBG\",\"description\":\"Powering the future\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/22hbg.com\\\/fr\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"L\u2019\u00e9ducation - 22HBG","description":"Pourquoi l\u2019\u00e9ducation dans le monde de la technologie ? Dans un secteur o\u00f9 l\u2019innovation est rapide, rester \u00e0 jour n\u2019est pas un avantage : c\u2019est une n\u00e9cessit\u00e9.C\u2019est pourquoi nous avons transform\u00e9 notre exp\u00e9rience en un cours de formation destin\u00e9 \u00e0 ceux qui veulent comprendre, planifier et conduire le changement.De la formation interne aux ateliers en","canonical_url":"https:\/\/22hbg.com\/fr\/leducation\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"mzzECBsCyHPEXBD4J7fk6YS6Kxma137XTchmt2Vyijg","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/22hbg.com\/fr\/leducation\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/22hbg.com\/fr\/#listItem","position":1,"name":"Home","item":"https:\/\/22hbg.com\/fr\/","nextItem":{"@type":"ListItem","@id":"https:\/\/22hbg.com\/fr\/leducation\/#listItem","name":"L&rsquo;\u00e9ducation"}},{"@type":"ListItem","@id":"https:\/\/22hbg.com\/fr\/leducation\/#listItem","position":2,"name":"L&rsquo;\u00e9ducation","previousItem":{"@type":"ListItem","@id":"https:\/\/22hbg.com\/fr\/#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/22hbg.com\/fr\/#organization","name":"22HBG","description":"Powering the future","url":"https:\/\/22hbg.com\/fr\/","email":"info@22hbg.com","telephone":"+393317316391","logo":{"@type":"ImageObject","url":"https:\/\/22hbg.com\/wp-content\/uploads\/2025\/01\/22hbg_favicon_logo.png","@id":"https:\/\/22hbg.com\/fr\/leducation\/#organizationLogo","width":512,"height":512,"caption":"22HBG"},"image":{"@id":"https:\/\/22hbg.com\/fr\/leducation\/#organizationLogo"}},{"@type":"WebPage","@id":"https:\/\/22hbg.com\/fr\/leducation\/#webpage","url":"https:\/\/22hbg.com\/fr\/leducation\/","name":"L\u2019\u00e9ducation - 22HBG","description":"Pourquoi l\u2019\u00e9ducation dans le monde de la technologie ? Dans un secteur o\u00f9 l\u2019innovation est rapide, rester \u00e0 jour n\u2019est pas un avantage : c\u2019est une n\u00e9cessit\u00e9.C\u2019est pourquoi nous avons transform\u00e9 notre exp\u00e9rience en un cours de formation destin\u00e9 \u00e0 ceux qui veulent comprendre, planifier et conduire le changement.De la formation interne aux ateliers en","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/22hbg.com\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/22hbg.com\/fr\/leducation\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/22hbg.com\/wp-content\/uploads\/2025\/05\/tx-control-card-bg.webp","@id":"https:\/\/22hbg.com\/fr\/leducation\/#mainImage","width":400,"height":600},"primaryImageOfPage":{"@id":"https:\/\/22hbg.com\/fr\/leducation\/#mainImage"},"datePublished":"2025-07-10T16:44:10+01:00","dateModified":"2025-12-15T11:32:49+01:00"},{"@type":"WebSite","@id":"https:\/\/22hbg.com\/fr\/#website","url":"https:\/\/22hbg.com\/fr\/","name":"22HBG","description":"Powering the future","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/22hbg.com\/fr\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"22HBG - Powering the future","og:type":"article","og:title":"L\u2019\u00e9ducation - 22HBG","og:description":"Pourquoi l\u2019\u00e9ducation dans le monde de la technologie ? Dans un secteur o\u00f9 l\u2019innovation est rapide, rester \u00e0 jour n\u2019est pas un avantage : c\u2019est une n\u00e9cessit\u00e9.C\u2019est pourquoi nous avons transform\u00e9 notre exp\u00e9rience en un cours de formation destin\u00e9 \u00e0 ceux qui veulent comprendre, planifier et conduire le changement.De la formation interne aux ateliers en","og:url":"https:\/\/22hbg.com\/fr\/leducation\/","article:published_time":"2025-07-10T15:44:10+00:00","article:modified_time":"2025-12-15T10:32:49+00:00","twitter:card":"summary_large_image","twitter:title":"L\u2019\u00e9ducation - 22HBG","twitter:description":"Pourquoi l\u2019\u00e9ducation dans le monde de la technologie ? Dans un secteur o\u00f9 l\u2019innovation est rapide, rester \u00e0 jour n\u2019est pas un avantage : c\u2019est une n\u00e9cessit\u00e9.C\u2019est pourquoi nous avons transform\u00e9 notre exp\u00e9rience en un cours de formation destin\u00e9 \u00e0 ceux qui veulent comprendre, planifier et conduire le changement.De la formation interne aux ateliers en"},"aioseo_meta_data":{"post_id":"26659","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2025-09-10 16:06:58","updated":"2025-12-15 10:33:55","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/22hbg.com\/fr\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tL\u2019\u00e9ducation\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/22hbg.com\/fr\/"},{"label":"L&rsquo;\u00e9ducation","link":"https:\/\/22hbg.com\/fr\/leducation\/"}],"_links":{"self":[{"href":"https:\/\/22hbg.com\/fr\/wp-json\/wp\/v2\/pages\/26659","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/22hbg.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/22hbg.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/22hbg.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/22hbg.com\/fr\/wp-json\/wp\/v2\/comments?post=26659"}],"version-history":[{"count":2,"href":"https:\/\/22hbg.com\/fr\/wp-json\/wp\/v2\/pages\/26659\/revisions"}],"predecessor-version":[{"id":29464,"href":"https:\/\/22hbg.com\/fr\/wp-json\/wp\/v2\/pages\/26659\/revisions\/29464"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/22hbg.com\/fr\/wp-json\/wp\/v2\/media\/24936"}],"wp:attachment":[{"href":"https:\/\/22hbg.com\/fr\/wp-json\/wp\/v2\/media?parent=26659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}